{"id":1693,"date":"2022-03-03T10:32:33","date_gmt":"2022-03-03T10:32:33","guid":{"rendered":"https:\/\/soexdemo.aiolos.solutions\/?page_id=1693"},"modified":"2022-06-17T10:37:26","modified_gmt":"2022-06-17T10:37:26","slug":"gold-spice-details","status":"publish","type":"page","link":"https:\/\/soexdemo.aiolos.solutions\/fr\/brands\/gold-spice-details\/","title":{"rendered":"Gold Spice D\u00e9tails"},"content":{"rendered":"\n<section class=\"customSection p-0 m-0\" id=\"GoldSpiceShowcase\">\n\t<img class=\"img-fluid brandDetailsSliderBg\" width=\"100%\" src=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/goldspice_bg-1.webp\">\n\t<div class=\"brandDetailsSlider\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"brandDetSlideMt\">&nbsp;<\/div>\n\t\t\t<div class=\"row flex-column-reverse flex-sm-row align-items-center\">\n\t\t\t\t<div class=\"col-sm-4 col-12 align-self-center\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<div class=\"col-12 text-center mt-sm-5\">\n\t\t\t\t\t\t\t<img class=\"img-fluid brandDetailsSlideText mb-3\" src=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/goldspice.webp\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<div class=\"col-12 text-center\">\n\t\t\t\t\t\t\t<h3 class=\"brandDetailSlideHeading\">M\u00c9LANGE D&#8217;\u00c9PICES DE LUXE<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-sm-8 col-12 text-right\">\n\t\t\t\t\t<img class=\"img-fluid\" src=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/gold_spice-4.webp\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"sectionBrandDetails\" style=\"border:none;\">\n\t<div class=\"container mb-5\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-sm-12 col-12\">\n\t\t\t\t<div class=\"brandDetailPara\">\n                    <span><b><i>Le Kretek du Roi !<\/i><\/b><\/span><br><br>Quand le luxe rencontre la magie &#8211; Un m\u00e9lange indulgent d&#8217;\u00e9pices exotiques con\u00e7u dans une cigarette de qualit\u00e9. Vivez le subliminal, vivez <span><b>Gold Spice<\/b><\/span><br>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"row flex-column-reverse flex-sm-row\">\n\t\t\t<div class=\"col-sm-5 text-center text-sm-left align-self-center revealR\">\t\t\t\t\n\t\t\t\t<img class=\"img-fluid brandLogoMargin\" src=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/goldspice1.webp\">\n\t\t\t\t<p class=\"brandDetailPara2 text-center mt-2\">84 MM<\/p>\n\t\t\t\t<img class=\"img-fluid\" src=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/Group-223.webp\">\n\t\t\t\t<p class=\"brandDetailPara2 mt-5\">M\u00c9LANGE : KRETEK<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-sm-7\">\n\t\t\t\t<div class=\"revealL\" style=\"width:100%;position:relative;\">\n\t\t\t\t\t<img class=\"img-fluid\" src=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/gold_spice.webp\">\t\t\t\t\t\n\t\t\t\t<\/div>\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t<\/div>\n<\/section>\n<section class=\"customSection brandBrochureWrap p-0 mb-5\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-sm-12 col-12 text-center\">\n\t\t\t\t<h1 class=\"brandBrochureHead\" style=\"color: #B5A268;\">\n                        <em>\u201cLE MONDE EST NOTRE MARCH\u00c9\u201d<\/em>\n                    <\/h1>\n\t\t\t\t<a class=\"anchorLink\" data-toggle=\"modal\" data-target=\"#downloadBrochureModal\" href=\"https:\/\/soexdemo.aiolos.solutions\/wp-content\/uploads\/2022\/03\/TheCatalogueCompressLatest.pdf\" download=\"\">T\u00e9l\u00e9charger la brochure<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<section class=\"sectionform mt-5\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-sm-6 pr-5 col-12\">\n\t\t\t\t<h1 class=\"headingMain\">MONTEZ<\/h1>\n\t\t\t\t<h2 class=\"headingSub\">TOUCHER  <\/h2>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-sm-12\">\n\t\t\t\t<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f4288-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/1693#wpcf7-f4288-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"4288\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4288-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"\">\n\t\t\t<span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required inputItem contactFormInput\" id=\"userName\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Entrez votre nom\" \/><\/span>\n\t\t<\/div>\n<div class=\" mt-3\">\n\t\t\t<span class=\"wpcf7-form-control-wrap your-company-name\"><input type=\"text\" name=\"your-company-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required inputItem contactFormInput\" id=\"userCompanyName\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Entrez le nom de votre entreprise\" \/><\/span>\n\t\t<\/div>\n<div class=\"mt-3 mb-sm-0 mb-3\">\n<span class=\"wpcf7-form-control-wrap phonetext-10\"><input type=\"text\" name=\"phonetext-10\" value=\"+91\" size=\"40\" maxlength=\"15\" minlength=\"10\" class=\"wpcf7-form-control wpcf7-text wpcf7-phonetext wpcf7-validates-as-required inputItem contactFormInput\" id=\"userMobile\" aria-required=\"true\" aria-invalid=\"false\" \/><input type=\"hidden\" name=\"phonetext-10-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span>\n\t\t<\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<div class=\"\">\n                 <span class=\"wpcf7-form-control-wrap title\"><input type=\"text\" name=\"title\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required inputItem contactFormInput\" id=\"userDesignation\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Entrez votre d\u00e9signation\" \/><\/span><\/div>\n<div class=\"mt-3\">\n<span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email inputItem contactFormInput\" id=\"userEmail\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Entrez votre identifiant de messagerie\" \/><\/span><\/div>\n<div class=\"mt-3 mb-sm-0 mb-3\">\n\t\t<span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"3\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required inputItem contactFormInput\" id=\"userMessage\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Entrez votre message ici...\"><\/textarea><\/span>\n               <\/div>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-6 col-12\">\n<div class=\"mb-3 pl-0 pt-3\">\n               <div id=\"cf7sr-6a58185d40d37\" class=\"cf7sr-g-recaptcha\" data-sitekey=\"6LfMzTkgAAAAADpIdWljd8-QUnQFAEdCdrEwugC1\"><\/div><span class=\"wpcf7-form-control-wrap cf7sr-recaptcha\"><input type=\"hidden\" name=\"cf7sr-recaptcha\" value=\"\" class=\"wpcf7-form-control\"><\/span>\n\t\t<\/div>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-12 mt-5 text-center\">\n\t\t<input type=\"submit\" value=\"Soumettre\" class=\"wpcf7-form-control has-spinner wpcf7-submit contactBtn2\" \/><\/p>\n<\/div>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\n\t<\/div>\t\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; M\u00c9LANGE D&#8217;\u00c9PICES DE LUXE Le Kretek du Roi ! Quand le luxe rencontre la magie &#8211; Un m\u00e9lange indulgent d&#8217;\u00e9pices exotiques con\u00e7u dans une cigarette de qualit\u00e9. Vivez le subliminal, vivez Gold Spice 84 MM M\u00c9LANGE : KRETEK \u201cLE MONDE EST NOTRE MARCH\u00c9\u201d T\u00e9l\u00e9charger la brochure MONTEZ TOUCHER<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":739,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width.php","meta":{"inline_featured_image":false},"translation":{"provider":"WPGlobus","version":"2.8.11","language":"fr","enabled_languages":["en","es","fr","ru","ar"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"ar":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/pages\/1693"}],"collection":[{"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/comments?post=1693"}],"version-history":[{"count":37,"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/pages\/1693\/revisions"}],"predecessor-version":[{"id":4766,"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/pages\/1693\/revisions\/4766"}],"up":[{"embeddable":true,"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/pages\/739"}],"wp:attachment":[{"href":"https:\/\/soexdemo.aiolos.solutions\/fr\/wp-json\/wp\/v2\/media?parent=1693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}